{"id":12836,"date":"2024-05-28T15:52:00","date_gmt":"2024-05-28T13:52:00","guid":{"rendered":"https:\/\/www.ensapc.fr\/dnsep\/"},"modified":"2024-08-29T10:39:59","modified_gmt":"2024-08-29T08:39:59","slug":"dnsep-2","status":"publish","type":"page","link":"https:\/\/www.ensapc.fr\/en\/artists\/diplome\/2024-2\/dnsep-2\/","title":{"rendered":"DNSEP"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]<div class=\"carousel-slider-outer carousel-slider-outer-image-carousel carousel-slider-outer-12322\" style=\"--carousel-slider-nav-color:#f1f1f1;--carousel-slider-active-nav-color:#00d1b2;--carousel-slider-arrow-size:48px;--carousel-slider-bullet-size:10px\">\n<div id=\"&#039;id-12322\" class=\"carousel-slider carousel-slider-12322 arrows-visibility-hover dots-visibility-never arrows-outside dots-center dots-circle owl-carousel\" data-slide-type=\"image-carousel\" data-owl-settings='{\"nav\":true,\"dots\":false,\"slideBy\":1,\"stagePadding\":50,\"margin\":10,\"loop\":true,\"lazyLoad\":false,\"autoplay\":true,\"autoplayTimeout\":5000,\"autoplaySpeed\":500,\"autoplayHoverPause\":true,\"autoWidth\":false,\"responsive\":{\"300\":{\"items\":1},\"576\":{\"items\":1},\"768\":{\"items\":1},\"1024\":{\"items\":1},\"1280\":{\"items\":1},\"1536\":{\"items\":1}}}'>\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9119-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9119-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9119-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9119-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9119.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">1express<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"960\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9138-768x1152.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9138-768x1152.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9138-200x300.jpg 200w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9138-683x1024.jpg 683w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9138.jpg 1000w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">1express<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9337-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9337-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9337-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9337-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9337.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Diane Audrain<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9304-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9304-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9304-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9304-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9304.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Diane Audrain<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9453-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9453-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9453-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9453-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9453.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Emma B. Lazli<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"960\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9464-768x1152.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9464-768x1152.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9464-200x300.jpg 200w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9464-683x1024.jpg 683w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9464.jpg 1000w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Emma B. Lazli<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9279-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9279-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9279-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9279-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9279.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Anna Nakhoul<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9265-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9265-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9265-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9265-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9265.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Anna Nakhoul<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9191-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9191-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9191-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9191-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9191.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Emma Durovray<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"960\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9213-768x1152.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9213-768x1152.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9213-200x300.jpg 200w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9213-683x1024.jpg 683w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9213.jpg 1000w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Emma Durovray<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"358\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1.-Ayda-capture-performance-768x430.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1.-Ayda-capture-performance-768x430.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1.-Ayda-capture-performance-300x168.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1.-Ayda-capture-performance-1024x573.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1.-Ayda-capture-performance.jpg 1430w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Ayda Kilinic<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"357\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2.ayda-capture-performance-768x428.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2.ayda-capture-performance-768x428.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2.ayda-capture-performance-300x167.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2.ayda-capture-performance-1024x571.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2.ayda-capture-performance.jpg 1431w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Ayda Kilinic<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9410-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9410-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9410-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9410-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9410.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Hendrik Gonzalez<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"960\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9413-768x1152.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9413-768x1152.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9413-200x300.jpg 200w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9413-683x1024.jpg 683w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9413.jpg 1000w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Hendrik Gonzalez<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"960\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9526-768x1152.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9526-768x1152.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9526-200x300.jpg 200w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9526-683x1024.jpg 683w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9526.jpg 1000w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Gral<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9591-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9591-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9591-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9591-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9591.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Gral<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Capture-decran-2024-05-30-a-11.52.19-768x432.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Capture-decran-2024-05-30-a-11.52.19-768x432.png 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Capture-decran-2024-05-30-a-11.52.19-300x169.png 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Capture-decran-2024-05-30-a-11.52.19-1024x575.png 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Capture-decran-2024-05-30-a-11.52.19.png 1429w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Jee Yeongseo<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"359\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Capture-decran-2024-05-30-a-11.43.55-768x431.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Capture-decran-2024-05-30-a-11.43.55-768x431.png 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Capture-decran-2024-05-30-a-11.43.55-300x168.png 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Capture-decran-2024-05-30-a-11.43.55-1024x574.png 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Capture-decran-2024-05-30-a-11.43.55.png 1311w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Jee Yeongseo<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"385\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/amphi-montage-768x462.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/amphi-montage-768x462.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/amphi-montage-300x180.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/amphi-montage-1024x616.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/amphi-montage-1536x923.jpg 1536w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/amphi-montage-2048x1231.jpg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Lucie Bonet<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"356\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/lag4-768x427.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/lag4-768x427.png 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/lag4-300x167.png 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/lag4-1024x570.png 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/lag4-1536x855.png 1536w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/lag4-2048x1140.png 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Lucie Bonet<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"358\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Raphael-capture-1-768x429.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Raphael-capture-1-768x429.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Raphael-capture-1-300x167.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Raphael-capture-1-1024x571.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Raphael-capture-1.jpg 1412w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Rapha\u00ebl Malezieux<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"358\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Raphael-capture-2-768x429.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Raphael-capture-2-768x429.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Raphael-capture-2-300x168.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Raphael-capture-2-1024x572.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/Raphael-capture-2.jpg 1399w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Rapha\u00ebl Malezieux<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9873_1-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9873_1-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9873_1-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9873_1-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9873_1.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Theo Nenning<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9936-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9936-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9936-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9936-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9936.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Theo Nenning<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9725-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9725-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9725-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9725-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9725.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Remy Chesnais<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9717-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9717-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9717-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9717-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9717.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Remy Chesnais<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9684-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9684-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9684-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9684-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9684.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\"> Camille Haccuria<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9768-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9768-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9768-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9768-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9768.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\"> Camille Haccuria<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0073-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0073-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0073-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0073-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0073.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Amine Habki<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"960\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9852-768x1152.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9852-768x1152.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9852-200x300.jpg 200w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9852-683x1024.jpg 683w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9852.jpg 1000w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Amine Habki<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/7-768x768.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/7-768x768.jpeg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/7-300x300.jpeg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/7-1024x1024.jpeg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/7-150x150.jpeg 150w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/7-1536x1536.jpeg 1536w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/7-427x427.jpeg 427w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/7-125x125.jpeg 125w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/7.jpeg 1619w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Emma Huang (capture film &quot;Anc\u00eatres de r\u00eave&quot;)<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/9-768x768.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/9-768x768.jpeg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/9-300x300.jpeg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/9-1024x1024.jpeg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/9-150x150.jpeg 150w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/9-1536x1536.jpeg 1536w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/9-427x427.jpeg 427w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/9-125x125.jpeg 125w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/9.jpeg 1619w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Emma Huang (capture film &quot;Anc\u00eatres de r\u00eave&quot;)<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9940-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9940-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9940-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9940-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9940.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Ferdinand Ledoux<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9949-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9949-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9949-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9949-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9949.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Ferdinand Ledoux<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0048-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0048-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0048-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0048-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0048.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Maxime Vignaud<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"960\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0038-768x1152.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0038-768x1152.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0038-200x300.jpg 200w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0038-683x1024.jpg 683w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0038.jpg 1000w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Maxime Vignaud<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0099-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0099-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0099-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0099-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0099.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Laura Dos Santos<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0106-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0106-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0106-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0106-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0106.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Laura Dos Santos<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9968-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9968-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9968-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9968-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9968.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Alina Izmailova<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9984-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9984-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9984-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9984-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A9984.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Alina Izmailova<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0195-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0195-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0195-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0195-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0195.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Isadora Guzniczak<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0154-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0154-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0154-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0154-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0154.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Isadora Guzniczak<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0456-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0456-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0456-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0456-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0456.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Nicolas Lebeau<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0463-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0463-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0463-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0463-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0463.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Nicolas Lebeau<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0784-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0784-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0784-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0784-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0784.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Sabrina Da Silva de Medeiros<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0785-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0785-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0785-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0785-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0785.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Sabrina Da Silva de Medeiros<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1.Elouan-Lebars-capture-du-film-22Peak-Performance22-768x432.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1.Elouan-Lebars-capture-du-film-22Peak-Performance22-768x432.png 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1.Elouan-Lebars-capture-du-film-22Peak-Performance22-300x169.png 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1.Elouan-Lebars-capture-du-film-22Peak-Performance22-1024x576.png 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1.Elouan-Lebars-capture-du-film-22Peak-Performance22-1536x864.png 1536w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1.Elouan-Lebars-capture-du-film-22Peak-Performance22-e1773239318797.png 800w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Elouan Lebars<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2.-Elouan-Lebars-capture-du-film-22Peak-Performance22-768x432.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2.-Elouan-Lebars-capture-du-film-22Peak-Performance22-768x432.png 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2.-Elouan-Lebars-capture-du-film-22Peak-Performance22-300x169.png 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2.-Elouan-Lebars-capture-du-film-22Peak-Performance22-1024x576.png 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2.-Elouan-Lebars-capture-du-film-22Peak-Performance22-1536x864.png 1536w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2.-Elouan-Lebars-capture-du-film-22Peak-Performance22-e1773239300711.png 800w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Elouan Lebars<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0858-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0858-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0858-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0858-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0858.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Maria Zaikina<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0886-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0886-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0886-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0886-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0886.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Maria Zaikina<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"960\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0553-768x1152.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0553-768x1152.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0553-200x300.jpg 200w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0553-683x1024.jpg 683w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0553.jpg 1000w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Claire Gentou<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"960\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0598-768x1152.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0598-768x1152.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0598-200x300.jpg 200w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0598-683x1024.jpg 683w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A0598.jpg 1000w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Claire Gentou<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1.Marie-Navarro-capture-768x432.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1.Marie-Navarro-capture-768x432.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1.Marie-Navarro-capture-300x169.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1.Marie-Navarro-capture-1024x576.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1.Marie-Navarro-capture.jpg 1078w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Marie Navarro<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"353\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2.Marie-Navarro-capture-768x423.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2.Marie-Navarro-capture-768x423.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2.Marie-Navarro-capture-300x165.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2.Marie-Navarro-capture-1024x564.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2.Marie-Navarro-capture.jpg 1430w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Marie Navarro<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"428\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/personnage-2\u00a9DFaksh-768x513.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/personnage-2\u00a9DFaksh-768x513.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/personnage-2\u00a9DFaksh-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/personnage-2\u00a9DFaksh-1024x684.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/personnage-2\u00a9DFaksh-1536x1025.jpg 1536w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/personnage-2\u00a9DFaksh-2048x1367.jpg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Diana Faksh<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"428\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/personnage-3\u00a9DFaksh-retouche-luminosite-1-768x513.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/personnage-3\u00a9DFaksh-retouche-luminosite-1-768x513.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/personnage-3\u00a9DFaksh-retouche-luminosite-1-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/personnage-3\u00a9DFaksh-retouche-luminosite-1-1024x684.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/personnage-3\u00a9DFaksh-retouche-luminosite-1-1536x1026.jpg 1536w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/personnage-3\u00a9DFaksh-retouche-luminosite-1-2048x1367.jpg 2048w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/personnage-3\u00a9DFaksh-retouche-luminosite-1-e1773239278983.jpg 1200w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Diana Faksh<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1202-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1202-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1202-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1202-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1202.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Leontine Guimard<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1188-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1188-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1188-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1188-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1188.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Leontine Guimard<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1051-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1051-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1051-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1051-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1051.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Ihsane Guyot<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"960\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1039-768x1152.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1039-768x1152.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1039-200x300.jpg 200w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1039-683x1024.jpg 683w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1039.jpg 1000w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Ihsane Guyot<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-1536x1024.jpg 1536w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-2048x1365.jpg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\"><\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2-1-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2-1-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2-1-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2-1-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/2-1.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Shumeng Li<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-bis-768x432.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-bis-768x432.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-bis-300x169.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-bis-1024x576.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-bis-1536x864.jpg 1536w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-bis.jpg 1920w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Gae\u0301tane Martinot<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/10-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/10-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/10-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/10-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/10-1536x1024.jpg 1536w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/10-2048x1365.jpg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Gae\u0301tane Martinot<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1590-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1590-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1590-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1590-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1590.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Esther Pezeron<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1594-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1594-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1594-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1594-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1594.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Esther Pezeron<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"960\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1582-768x1152.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1582-768x1152.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1582-200x300.jpg 200w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1582-683x1024.jpg 683w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1582.jpg 1000w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Adele Ballif<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1396-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1396-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1396-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1396-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1396.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Adele Ballif<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"499\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-1-768x599.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-1-768x599.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-1-300x234.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-1-1024x799.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-1-1536x1199.jpg 1536w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/1-1-2048x1598.jpg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Lila Frejaville<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"438\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/3-768x526.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/3-768x526.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/3-300x206.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/3-1024x702.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/3-1536x1052.jpg 1536w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/3-2048x1403.jpg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Lila Frejaville<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1284-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1284-768x512.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1284-300x200.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1284-1024x683.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/6R7A1284.jpg 1500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Yourk Salzard<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/9-768x432.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/9-768x432.jpg 768w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/9-300x169.jpg 300w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/9-1024x576.jpg 1024w, https:\/\/www.ensapc.fr\/wp-content\/uploads\/2024\/06\/9.jpg 1115w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Yourk Salzard<\/p><\/div><\/a><\/div>\n\n<\/div><!-- .carousel-slider-12322 -->\n<\/div><!-- .carousel-slider-outer-12322 -->\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;&#8221;]Photos par Nadia Ermakova <a href=\"https:\/\/www.instagram.com\/ermakovakova\/\">@ermakovakova<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;][\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;&#8221;]Photos par Nadia Ermakova @ermakovakova[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":12762,"menu_order":164,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-12836","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.ensapc.fr\/en\/wp-json\/wp\/v2\/pages\/12836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ensapc.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ensapc.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ensapc.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ensapc.fr\/en\/wp-json\/wp\/v2\/comments?post=12836"}],"version-history":[{"count":1,"href":"https:\/\/www.ensapc.fr\/en\/wp-json\/wp\/v2\/pages\/12836\/revisions"}],"predecessor-version":[{"id":12837,"href":"https:\/\/www.ensapc.fr\/en\/wp-json\/wp\/v2\/pages\/12836\/revisions\/12837"}],"up":[{"embeddable":true,"href":"https:\/\/www.ensapc.fr\/en\/wp-json\/wp\/v2\/pages\/12762"}],"wp:attachment":[{"href":"https:\/\/www.ensapc.fr\/en\/wp-json\/wp\/v2\/media?parent=12836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}